{"id":6812,"date":"2019-07-05T12:04:53","date_gmt":"2019-07-05T10:04:53","guid":{"rendered":"http:\/\/www.tv2000.it\/docfilm\/?p=6812"},"modified":"2019-06-24T12:54:09","modified_gmt":"2019-06-24T10:54:09","slug":"amelia-la-vita-della-famosa-pioniera-dellaviazione-femminile-amelia-earhart","status":"publish","type":"post","link":"https:\/\/www.tv2000.it\/docfilm\/2019\/07\/05\/amelia-la-vita-della-famosa-pioniera-dellaviazione-femminile-amelia-earhart\/","title":{"rendered":"Amelia,<br>la vita della famosa pioniera dell&#8217;aviazione femminile"},"content":{"rendered":"<p><b><a href=\"https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/Amelia_1528x2162_IT_KAwT.jpg\"><img decoding=\"async\" class=\"size-large wp-image-6817 alignleft\" src=\"https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/Amelia_1528x2162_IT_KAwT-724x1024.jpg\" alt=\"\" width=\"640\" height=\"905\" srcset=\"https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/Amelia_1528x2162_IT_KAwT-724x1024.jpg 724w, https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/Amelia_1528x2162_IT_KAwT-212x300.jpg 212w, https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/Amelia_1528x2162_IT_KAwT-768x1087.jpg 768w, https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/Amelia_1528x2162_IT_KAwT-19x27.jpg 19w, https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/Amelia_1528x2162_IT_KAwT-280x396.jpg 280w, https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/Amelia_1528x2162_IT_KAwT-650x920.jpg 650w, https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/Amelia_1528x2162_IT_KAwT.jpg 1528w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>Domenica 14 luglio alle 21.15 su Tv2000<\/b><i><b> &#8211; Amelia<\/b><\/i>&nbsp;\u00e8 un film del&nbsp;2009&nbsp;diretto da&nbsp;Mira Nair.&nbsp;\u00c8 narrata parte della vita della famosa pioniera dell&#8217;aviazione femminile&nbsp;Amelia Earhart, interpretata dalla due volte&nbsp;Premio Oscar&nbsp;Hilary Swank, la quale ha inoltre una incredibile somiglianza con la Earhart. La regista indiana Mira Nair ha girato questo&nbsp;film biografico&nbsp;su una sceneggiatura di&nbsp;Ronald Bass&nbsp;e&nbsp;Anna Hamilton Phelan&nbsp;ispirata a varie biografie realizzate sulla Earhart.<\/p>\n<p>La Swank ha vinto il premio come&nbsp;<i>Migliore attrice<\/i>&nbsp;all&#8217;Hollywood Film Festival&nbsp;2009.&nbsp;Il cast comprende anche&nbsp;Richard Gere&nbsp;nel ruolo di George Putnam, il marito della Earhart,&nbsp;Ewan McGregor&nbsp;che interpreta l&#8217;atleta e pilota&nbsp;Gene Vidal&nbsp;(con il quale la Earhart ebbe una tormentata storia d&#8217;amore),&nbsp;Virginia Madsen,&nbsp;Mia Wasikowska&nbsp;e&nbsp;Christopher Eccleston.<\/p>\n<p>Amelia Earhart&nbsp;\u00e8 una giovane aviatrice che, nel&nbsp;1928, per iniziativa del magnate dell&#8217;informazione George Putnam, ad un solo anno di distanza dal primo viaggio transatlantico in solitaria di&nbsp;Charles Lindbergh, dapprima compie lo stesso percorso come passeggera, poi lo effettua in solitaria. Stabilisce cos\u00ec in rapida successione il primato di prima donna a sorvolare l&#8217;oceano Atlantico&nbsp;e quindi di prima donna ad effettuare in solitaria un viaggio transatlantico.&nbsp;I continui record infranti, grazie anche all&#8217;efficace&nbsp;<i>battage<\/i>&nbsp;pubblicitario messo su da Putnam, che intanto \u00e8 diventato suo marito, danno alla Earhart una fama mondiale facendola assurgere ad una sorta di eroina nazionale.&nbsp;Amelia, sempre impegnata nella promozione dell&#8217;aviazione, intrattiene poi una relazione con l&#8217;ex atleta e pilota&nbsp;Gene Vidal&nbsp;che le riserver\u00e0 un posto di particolare importanza nella compagnia aerea che ha costituito. Suo marito, che ormai organizzava sempre meno voli avventurosi preferendo per la moglie eventi promozionali e pubblicit\u00e0, anche per riconquistarne l&#8217;amore si adopera per organizzarle il sogno della vita, il viaggio intorno al mondo. Amelia lascia cos\u00ec Vidal e si getta anima e corpo nella nuova impresa. Questa, una volta trovati i fondi, presenta comunque la non trascurabile difficolt\u00e0 tecnica di dover trasvolare l&#8217;Oceano Pacifico&nbsp;che presenta cos\u00ec pochi approdi da costringere a delle tappe molto complesse per lunghezza e raggiungibilit\u00e0 dei siti.&nbsp;Dopo un primo tentativo fallito direttamente al decollo, dalle isole&nbsp;Hawaii, si decide comunque di perseguire il progetto effettuando diverse correzioni, come la direzione di rotta che viene invertita, facendo risultare cos\u00ec l&#8217;Oceano Pacifico al termine del giro del globo. Dopo settimane di perfetta navigazione attorno al mondo, la Earhart e il suo navigatore Fred Noonan, si devono presentare a quello che \u00e8 il passaggio pi\u00f9 pericoloso del loro viaggio, il rifornimento presso la minuscola&nbsp;isola Howland. Provando a raggiungere la stessa, dopo numerosi febbrili tentativi di contatto radio, il 2 luglio&nbsp;<a title=\"1937\" href=\"https:\/\/it.wikipedia.org\/wiki\/1937\">1937<\/a>, le flebili trasmissioni provenienti dal volo si interrompono definitivamente. La pioniera dell&#8217;aviazione Amelia Earhart, scompare nel nulla con il suo aereo e il suo navigatore, quando non ha compiuto ancora 40 anni. Nonostante una imponente azione di ricerca intrapresa dalla marina e dalla aviazione statunitense, non sar\u00e0 trovata pi\u00f9 alcuna traccia n\u00e9 del veicolo, n\u00e9 dei due sfortunati occupanti.<\/p>\n","protected":false},"excerpt":{"rendered":"Domenica 14 luglio alle 21.15 su Tv2000 &#8211; Amelia&nbsp;\u00e8 un film del&nbsp;2009&nbsp;diretto da&nbsp;Mira Nair.&nbsp;\u00c8 narrata parte della vita della famosa pioniera dell&#8217;aviazione femminile&nbsp;Amelia Earhart, interpretata dalla due volte&nbsp;Premio Oscar&nbsp;Hilary Swank, la quale ha inoltre una incredibile somiglianza con la Earhart. La regista indiana Mira Nair ha girato questo&nbsp;film biografico&nbsp;su una sceneggiatura di&nbsp;Ronald Bass&nbsp;e&nbsp;Anna Hamilton Phelan&nbsp;ispirata [&hellip;]","protected":false},"author":35,"featured_media":6815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[12,374,371,373,372,15],"class_list":["post-6812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-film-in-programmazione","tag-film","tag-amelia","tag-amelia-earhart","tag-hilary-swank","tag-richard-gere","tag-tv2000"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/www.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/10\/88original-e1540395222175-1024x1024.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/6812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=6812"}],"version-history":[{"count":4,"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/6812\/revisions"}],"predecessor-version":[{"id":8400,"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/6812\/revisions\/8400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/6815"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=6812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=6812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=6812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}