{"id":11480,"date":"2019-10-10T18:36:31","date_gmt":"2019-10-10T16:36:31","guid":{"rendered":"http:\/\/www.tv2000.it\/ildiariodipapafrancesco\/?p=11480"},"modified":"2019-10-10T18:36:50","modified_gmt":"2019-10-10T16:36:50","slug":"la-settimana-della-bellezza","status":"publish","type":"post","link":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/2019\/10\/10\/la-settimana-della-bellezza\/","title":{"rendered":"La Settimana della Bellezza"},"content":{"rendered":"<p>Ospite di Gennaro Ferrara, Mons. Rodolfo Cetoloni, vescovo di Grosseto, e don Roberto Nelli, responsabile ufficio cultura Diocesi di Grosseto, presentano la 4\u00b0 Edizione della Settimana della Bellezza, dedicata quest&#8217;anno alla Bellezza della parola, suggerito dal documento della Conferenza Episcopale Toscana \u201cLa forza della parola\u201d.<\/p>\n<p>L&#8217;evento avr\u00e0 luogo dal 18 al 27 ottobre 2019.<\/p>\n<p>PUNTATA INTEGRALE<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Il diario di Papa Francesco, 10 ottobre 2019\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/eMN8yz4NiWM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p><a href=\"http:\/\/w2.vatican.va\/content\/francesco\/it\/speeches\/2018\/february\/documents\/papa-francesco_20180224_diaconie-de-la-beaute.html\" target=\"_blank\" rel=\"noopener\">Papa Francesco, Servire la Bellezza<\/a><br \/>\nLa vostra ricerca della bellezza in ci\u00f2 che voi create sia animata dal desiderio di servire la bellezza della qualit\u00e0 della vita delle persone, della loro armonia con l\u2019ambiente, dell\u2019incontro e dell\u2019aiuto reciproco (cfr ibid., 150). Vi incoraggio dunque, in questa \u201cDiaconia della Bellezza\u201d, a promuovere una cultura dell\u2019incontro, a costruire ponti tra le persone, tra i popoli, in un mondo in cui si innalzano ancora tanti muri per paura degli altri. Abbiate a cuore anche di testimoniare, nell\u2019espressione della vostra arte, che credere in Ges\u00f9 Cristo e seguirlo \u00abnon \u00e8 solamente una cosa vera e giusta, ma anche bella, capace di colmare la vita di un nuovo splendore e di una gioia profonda, anche in mezzo alle prove\u00bb<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Papa Francesco, Servire la Bellezza\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/gfgRc3NW9VE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p><a href=\"https:\/\/press.vatican.va\/content\/salastampa\/it\/bollettino\/pubblico\/2013\/03\/16\/0155\/00377.html\" target=\"_blank\" rel=\"noopener\">Papa Francesco, \u201cLa Chiesa esiste per comunicare verit\u00e0, bont\u00e0 e bellezza\u201d<\/a><\/p>\n<p>Il vostro lavoro necessita di studio, di sensibilit\u00e0, di esperienza, come tante altre professioni, ma comporta una particolare attenzione nei confronti della verit\u00e0, della bont\u00e0 e della bellezza; e questo ci rende particolarmente vicini, perch\u00e9 la Chiesa esiste per comunicare proprio questo: la Verit\u00e0, la Bont\u00e0 e la Bellezza &#8220;in persona&#8221;.<br \/>\nDovrebbe apparire chiaramente che siamo chiamati tutti non a comunicare noi stessi, ma questa triade esistenziale che conformano verit\u00e0, bont\u00e0 e bellezza.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Papa Francesco, \u201cLa Chiesa esiste per comunicare verit\u00e0, bont\u00e0 e bellezza\u201d\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/I1WUtyYfRtk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p><a href=\"https:\/\/press.vatican.va\/content\/salastampa\/it\/bollettino\/pubblico\/2018\/09\/28\/0703\/01500.html\" target=\"_blank\" rel=\"noopener\">Papa Francesco, Quando \u00e8 l\u2019arte a testimoniare il Signore<\/a><br \/>\nL\u2019arte, nella storia, \u00e8 stata seconda solo alla vita nel testimoniare il Signore. Infatti \u00e8 stata, ed \u00e8, una via maestra che permette di accedere alla fede pi\u00f9 di tante parole e idee, perch\u00e9 con la fede condivide il medesimo sentiero, quello della bellezza. \u00c8 una bellezza, quella dell\u2019arte, che fa bene alla vita e crea comunione: perch\u00e9 unisce Dio, l\u2019uomo e il creato in un\u2019unica sinfonia; perch\u00e9 congiunge il passato, il presente e l\u2019avvenire; perch\u00e9 attira nello stesso luogo e coinvolge nel medesimo sguardo genti diverse e popoli distanti.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Papa Francesco, Quando \u00e8 l\u2019arte a testimoniare il Signore\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/XTigFgj8HI4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>IN EVIDENZA:<\/p>\n<p>Mons. Rodolfo Cetoloni: \u201cSi \u00e8 belli quando si \u00e8 veri\u201d<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Mons. Rodolfo Cetoloni: \u201cSi \u00e8 belli quando si \u00e8 veri\u201d\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/mGdhNDfQDK8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Ospite di Gennaro Ferrara, Mons. Rodolfo Cetoloni, vescovo di Grosseto, e don Roberto Nelli, responsabile ufficio cultura Diocesi di Grosseto, presentano la 4\u00b0 Edizione della Settimana della Bellezza, dedicata quest&#8217;anno alla Bellezza della parola, suggerito dal documento della Conferenza Episcopale Toscana \u201cLa forza della parola\u201d. L&#8217;evento avr\u00e0 luogo dal 18 al 27 ottobre 2019. PUNTATA [&hellip;]","protected":false},"author":9,"featured_media":11481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[131],"tags":[41],"class_list":["post-11480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puntate-dal-2017-al-2020","tag-papafrancesco"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2019\/10\/diario1010-1024x576.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/11480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/comments?post=11480"}],"version-history":[{"count":1,"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/11480\/revisions"}],"predecessor-version":[{"id":11482,"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/11480\/revisions\/11482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media\/11481"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media?parent=11480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/categories?post=11480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/tags?post=11480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}