{"id":1352,"date":"2016-02-26T11:42:09","date_gmt":"2016-02-26T10:42:09","guid":{"rendered":"http:\/\/www.tv2000.it\/ilmiomedico\/?post_type=video&#038;p=1352"},"modified":"2016-02-26T11:42:09","modified_gmt":"2016-02-26T10:42:09","slug":"le-straordinarie-proprieta-dellarancia-rossa-di-palagonia-ct","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/ilmiomedico\/video\/le-straordinarie-proprieta-dellarancia-rossa-di-palagonia-ct\/","title":{"rendered":"Le straordinarie propriet\u00e0 dell&#8217;arancia rossa di Palagonia (CT)"},"content":{"rendered":"<p>Le straordinarie propriet\u00e0 dell&#8217;arancia rossa di Palagonia (CT). Dalla puntata de Il mio medico del 26 febbraio 2016 condotta da Monica Di Loreto.<\/p>\n","protected":false},"featured_media":1353,"comment_status":"open","ping_status":"open","template":"","tags":[],"class_list":["post-1352","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-clip"],"acf":[],"aioseo_notices":[],"url_youtube":"D4sHwkp7gA8","featured_image_url":"https:\/\/i.ytimg.com\/vi\/D4sHwkp7gA8\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/video\/1352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/comments?post=1352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/media\/1353"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/media?parent=1352"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/tags?post=1352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}