{"id":4463,"date":"2020-01-07T15:13:51","date_gmt":"2020-01-07T14:13:51","guid":{"rendered":"http:\/\/www.tv2000.it\/quelchepassailconvento\/?post_type=video&#038;p=4463"},"modified":"2020-01-07T15:13:51","modified_gmt":"2020-01-07T14:13:51","slug":"intervista-allo-chef-mario-salaris-5","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/quelchepassailconvento\/video\/intervista-allo-chef-mario-salaris-5\/","title":{"rendered":"Intervista allo chef Mario Salaris"},"content":{"rendered":"<p>Intervista allo chef Mario Salaris \u2013 ristorante \u201cFERRO E GHISA\u201d di Roma realizzata da Francesca Ceci: torta di ricotta e visciole<\/p>\n","protected":false},"featured_media":4464,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-4463","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-in-cucina-con-lo-chef"],"acf":[],"aioseo_notices":[],"url_youtube":"XJRFSujqVbo","featured_image_url":"https:\/\/i.ytimg.com\/vi\/XJRFSujqVbo\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/quelchepassailconvento\/wp-json\/wp\/v2\/video\/4463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/quelchepassailconvento\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/quelchepassailconvento\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/quelchepassailconvento\/wp-json\/wp\/v2\/comments?post=4463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/quelchepassailconvento\/wp-json\/wp\/v2\/media\/4464"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/quelchepassailconvento\/wp-json\/wp\/v2\/media?parent=4463"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/quelchepassailconvento\/wp-json\/wp\/v2\/tags?post=4463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}