{"id":235929,"date":"2023-06-15T13:08:52","date_gmt":"2023-06-15T11:08:52","guid":{"rendered":"https:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=235929"},"modified":"2023-06-15T15:54:26","modified_gmt":"2023-06-15T13:54:26","slug":"papa-al-gemelli-prosegue-la-convalescenza-tra-lavoro-e-preghiera","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/papa-al-gemelli-prosegue-la-convalescenza-tra-lavoro-e-preghiera\/","title":{"rendered":"Papa al Gemelli, convalescenza tra lavoro e preghiera"},"content":{"rendered":"<p>Papa Francesco sta proseguendo la convalescenza al Policlinico Gemelli, alternando riposo, preghiera e attivit\u00e0 lavorativa, nonch\u00e9 recupero clinico. I medici stanno valutando di dimetterlo dall&#8217;ospedale nei prossimi giorni. Stamane visita di Francesco ai malati oncologici. In collegamento Paolo Fucili.<\/p>\n","protected":false},"featured_media":235930,"comment_status":"closed","ping_status":"closed","template":"","tags":[2245],"class_list":["post-235929","video","type-video","status-publish","has-post-thumbnail","hentry","tag-papainospedale","video_category-news","video_category-papa-francesco"],"acf":[],"aioseo_notices":[],"url_youtube":"eiRnYEe3fbE","featured_image_url":"https:\/\/i.ytimg.com\/vi\/eiRnYEe3fbE\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/235929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=235929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/235930"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=235929"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=235929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}