{"id":256645,"date":"2023-09-04T19:36:03","date_gmt":"2023-09-04T17:36:03","guid":{"rendered":"https:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=256645"},"modified":"2023-09-04T19:36:03","modified_gmt":"2023-09-04T17:36:03","slug":"viaggio-in-mongolia-lintervista-di-francesco-sul-volo-di-ritorno","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/viaggio-in-mongolia-lintervista-di-francesco-sul-volo-di-ritorno\/","title":{"rendered":"Viaggio in Mongolia, l\u2019intervista di Francesco sul volo di ritorno"},"content":{"rendered":"<p>Papa Francesco \u00e8 rientrato in Vaticano dal viaggio in Mongolia.<br \/>\nDurante la consueta conferenza stampa ad alta quota ha parlato della Cina: i rapporti sono molto rispettosi, ha detto. Sulla Russia ha spiegato: \u201cNon si deve cancellare la cultura di un paese per motivi politici. Poi ha messo in guardia dalle ideologie.<br \/>\nSempre pi\u00f9 difficile per me viaggiare, ha confidato, sopratutto a causa della sua difficolt\u00e0 a camminare.<br \/>\nServizio di Cristiana Caricato<\/p>\n","protected":false},"featured_media":256646,"comment_status":"closed","ping_status":"closed","template":"","tags":[443],"class_list":["post-256645","video","type-video","status-publish","has-post-thumbnail","hentry","tag-papafrancesco","video_category-news","video_category-papa-francesco"],"acf":[],"aioseo_notices":[],"url_youtube":"0OTvv986p5Q","featured_image_url":"https:\/\/i.ytimg.com\/vi\/0OTvv986p5Q\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/256645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=256645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/256646"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=256645"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=256645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}