{"id":258972,"date":"2023-09-09T19:27:48","date_gmt":"2023-09-09T17:27:48","guid":{"rendered":"https:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=258972"},"modified":"2023-09-09T19:44:24","modified_gmt":"2023-09-09T17:44:24","slug":"in-memoria-della-corazzata-roma-mattarella-allasinara","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/in-memoria-della-corazzata-roma-mattarella-allasinara\/","title":{"rendered":"In memoria della Corazzata Roma, Mattarella all\u2019Asinara"},"content":{"rendered":"<p>Questa mattina la commemorazione dell&#8217;ottantesimo anniversario dell&#8217;affondamento della Corazzata Roma alla presenza del presidente della Repubblica Sergio Mattarella. La nave ammiraglia della regia marina affond\u00f2 nel Golfo dell&#8217;Asinara il 9 settembre del 1943 attaccata dai bombardieri tedeschi il giorno dopo l&#8217;armistizio. Il servizio di Clara Iatosti.<\/p>\n","protected":false},"featured_media":258973,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-258972","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-cronaca","video_category-news"],"acf":[],"aioseo_notices":[],"url_youtube":"MT0ptGfDpeg","featured_image_url":"https:\/\/i.ytimg.com\/vi\/MT0ptGfDpeg\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/258972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=258972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/258973"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=258972"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=258972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}