{"id":33892,"date":"2018-04-10T19:58:56","date_gmt":"2018-04-10T17:58:56","guid":{"rendered":"http:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=33892"},"modified":"2018-04-11T10:47:01","modified_gmt":"2018-04-11T08:47:01","slug":"cultura-restaurata-abbazia-di-santa-maria-errate-a-lecce-e-tra-le-bellezze-ditalia","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/cultura-restaurata-abbazia-di-santa-maria-errate-a-lecce-e-tra-le-bellezze-ditalia\/","title":{"rendered":"Cultura: restaurata abbazia di Santa Maria Cerrate a Lecce. E\u2019 tra le bellezze d\u2019Italia"},"content":{"rendered":"<p>L\u2019abbazia di Santa Maria Cerrate, in Provincia di Lecce, una bellezza che il Fondo ambiente italiano, il Fai, ha finito da poco di restaurare ridando cosi la possibilit\u00e0 ai fedeli di pregare tra le mura di una delle bellezze dell\u2019Italia.<\/p>\n","protected":false},"featured_media":33893,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-33892","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-attualita","video_category-news","tipologia-clip"],"acf":[],"aioseo_notices":[],"url_youtube":"Sijtg933AHI","featured_image_url":"https:\/\/i.ytimg.com\/vi\/Sijtg933AHI\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/33892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=33892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/33893"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=33892"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=33892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}