{"id":34062,"date":"2018-04-17T14:01:50","date_gmt":"2018-04-17T12:01:50","guid":{"rendered":"http:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=34062"},"modified":"2018-04-17T14:01:58","modified_gmt":"2018-04-17T12:01:58","slug":"abano-terme-convegno-nazionale-caritas-diocesane-le-parole-del-cardinale-bassetti","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/abano-terme-convegno-nazionale-caritas-diocesane-le-parole-del-cardinale-bassetti\/","title":{"rendered":"Abano Terme, Convegno nazionale Caritas diocesane: le parole del cardinale Bassetti"},"content":{"rendered":"<p>I giovani vanno accompagnati e accolti e non messi in competizione sfrenata, frustrati e demotivati. Sono le parole del cardinal Bassetti, presidente della CEI, parlando alle Caritas diocesane d&#8217;Italia raccolte in convegno nazionale ad Abano Terme nel padovano. Servizio di Fabio Bolzetta<\/p>\n","protected":false},"featured_media":34063,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-34062","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-chiesa"],"acf":[],"aioseo_notices":[],"url_youtube":"br0G8YRrRTg","featured_image_url":"https:\/\/i.ytimg.com\/vi\/br0G8YRrRTg\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/34062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=34062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/34063"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=34062"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=34062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}