{"id":34523,"date":"2018-05-02T13:08:26","date_gmt":"2018-05-02T11:08:26","guid":{"rendered":"http:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=34523"},"modified":"2018-05-02T13:08:37","modified_gmt":"2018-05-02T11:08:37","slug":"a-loppiano-il-genfest-italia-3500-giovani-da-tutta-italia-aspettando-la-visita-di-papa-francesco","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/a-loppiano-il-genfest-italia-3500-giovani-da-tutta-italia-aspettando-la-visita-di-papa-francesco\/","title":{"rendered":"A Loppiano il &#8220;Genfest Italia&#8221;: 3500 giovani da tutta Italia, aspettando la visita di Papa Francesco"},"content":{"rendered":"<p>Manca poco pi\u00f9 di una settimana dalla visita del Papa a Loppiano e la cittadella dei focolari in Toscana ha accolto migliaia di giovani per il Gen Fest. E a loro \u00e8 arrivato anche un messaggio dal Papa per &#8220;essere ovunque artefici di pace e di speranza&#8221;. Servizio di Diletta D&#8217;Agostini<\/p>\n","protected":false},"featured_media":34524,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-34523","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-chiesa"],"acf":[],"aioseo_notices":[],"url_youtube":"WvfSD0Orn3w","featured_image_url":"https:\/\/i.ytimg.com\/vi\/WvfSD0Orn3w\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/34523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=34523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/34524"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=34523"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=34523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}