{"id":35064,"date":"2018-05-18T19:43:00","date_gmt":"2018-05-18T17:43:00","guid":{"rendered":"http:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=35064"},"modified":"2018-05-18T19:46:21","modified_gmt":"2018-05-18T17:46:21","slug":"bambina-di-un-anno-morta-in-auto-a-pisa-il-padre-la-dimentica-nel-parcheggio","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/bambina-di-un-anno-morta-in-auto-a-pisa-il-padre-la-dimentica-nel-parcheggio\/","title":{"rendered":"Bambina di un anno morta in auto a Pisa: il padre la dimentica nel parcheggio"},"content":{"rendered":"<p>Ancora una volta un tragico episodio di un genitore che dimentica, in questo caso la figlia di appena un anno in macchina e va a lavorare. \u00c8 accaduto a Pisa nel parcheggio di uno stabilimento. L&#8217;allarme \u00e8 scattato intorno alle 16, ma quando sono arrivati i soccorritori la piccola era gi\u00e0 morta. Servizio di Marco Bergamaschi<\/p>\n","protected":false},"featured_media":35065,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-35064","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-cronaca","video_category-news"],"acf":[],"aioseo_notices":[],"url_youtube":"iA5q-HboRPI","featured_image_url":"https:\/\/i.ytimg.com\/vi\/iA5q-HboRPI\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/35064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=35064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/35065"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=35064"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=35064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}