{"id":35774,"date":"2018-06-09T19:33:41","date_gmt":"2018-06-09T17:33:41","guid":{"rendered":"http:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=35774"},"modified":"2018-06-11T12:09:25","modified_gmt":"2018-06-11T10:09:25","slug":"papa-francesco-ai-petrolieri-energia-per-tutti-senza-squilibri-ambientali","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/papa-francesco-ai-petrolieri-energia-per-tutti-senza-squilibri-ambientali\/","title":{"rendered":"Papa Francesco ai petrolieri: energia per tutti senza squilibri ambientali"},"content":{"rendered":"<p>Il Papa ha incontrato in Vaticano un gruppo di dirigenti di imprese petrolifere e del settore energetico. Richiamando l&#8217;enciclica Laudato s\u00ec, Francesco ha invitato al rispetto dell&#8217;ambiente e degli ecosistemi, e ha parlato degli effetti del riscaldamento globale che si ripercuotono soprattutto sui poveri. Servizio di Francesco Durante<\/p>\n","protected":false},"featured_media":35775,"comment_status":"closed","ping_status":"closed","template":"","tags":[443],"class_list":["post-35774","video","type-video","status-publish","has-post-thumbnail","hentry","tag-papafrancesco","video_category-papa-francesco"],"acf":[],"aioseo_notices":[],"url_youtube":"ZDt3ewY3KFk","featured_image_url":"https:\/\/i.ytimg.com\/vi\/ZDt3ewY3KFk\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/35774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=35774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/35775"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=35774"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=35774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}