{"id":53424,"date":"2019-09-18T19:47:26","date_gmt":"2019-09-18T17:47:26","guid":{"rendered":"http:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=53424"},"modified":"2019-09-18T19:47:26","modified_gmt":"2019-09-18T17:47:26","slug":"la-nuova-farmacia-di-strada-a-roma-ecco-come-funziona","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/la-nuova-farmacia-di-strada-a-roma-ecco-come-funziona\/","title":{"rendered":"La nuova farmacia di strada a Roma. Ecco come funziona"},"content":{"rendered":"<p>Sono sempre di pi\u00f9 purtroppo gli italiani costretti a rinunciare a prestazioni e cure mediche. Per povert\u00e0. Tra loro ci sono gli ultimi tra gli ultimi, quelli che vivono per strada e non hanno nemmeno i soldi per un&#8217;aspirina. Ed \u00e8 dunque pensata proprio per loro la &#8220;farmacia di strada&#8221; inaugurata a Roma nei locali dell&#8217;ambulatorio del centro di accoglienza gestito dai volontari del vicino carcere di Regina Coeli. Servizio di Nicola Ferrante<\/p>\n","protected":false},"featured_media":53425,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-53424","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-news"],"acf":[],"aioseo_notices":[],"url_youtube":"qNljegaLQP0","featured_image_url":"https:\/\/i.ytimg.com\/vi\/qNljegaLQP0\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/53424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=53424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/53425"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=53424"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=53424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}