{"id":82205,"date":"2021-12-22T13:46:53","date_gmt":"2021-12-22T12:46:53","guid":{"rendered":"http:\/\/www.tv2000.it\/tg2000\/?post_type=video&#038;p=82205"},"modified":"2021-12-22T13:59:10","modified_gmt":"2021-12-22T12:59:10","slug":"a-terza-pagina-la-scimmia-sulla-culla-di-angela-iantosca-e-fallin-in-the-dark-di-statale-66","status":"publish","type":"video","link":"https:\/\/www.tv2000.it\/tg2000\/video\/a-terza-pagina-la-scimmia-sulla-culla-di-angela-iantosca-e-fallin-in-the-dark-di-statale-66\/","title":{"rendered":"A Terza Pagina &#8216;La scimmia sulla culla&#8217; di Angela Iantosca e &#8220;Fallin&#8217; in the Dark&#8221; di Statale 66"},"content":{"rendered":"<p>A Terza Pagina il libro &#8216;La scimmia sulla culla. Bambini in crisi di astinenza&#8217; di Angela Iantosca e il singolo &#8220;Fallin&#8217; in the Dark&#8221; di Statale 66.<\/p>\n","protected":false},"featured_media":82206,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-82205","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-terza-pagina"],"acf":[],"aioseo_notices":[],"url_youtube":"iQcc3KD-aVI","featured_image_url":"https:\/\/i.ytimg.com\/vi\/iQcc3KD-aVI\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/82205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=82205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/82206"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=82205"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=82205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}