{"id":224154,"date":"2025-01-10T16:59:00","date_gmt":"2025-01-10T15:59:00","guid":{"rendered":"https:\/\/www.tv2000.it\/ufficiostampa\/?p=224154"},"modified":"2025-01-10T17:50:31","modified_gmt":"2025-01-10T16:50:31","slug":"medio-oriente-card-parolin-non-sono-conflitti-insolubili","status":"publish","type":"post","link":"https:\/\/www.tv2000.it\/ufficiostampa\/2025\/01\/10\/medio-oriente-card-parolin-non-sono-conflitti-insolubili\/","title":{"rendered":"Medio Oriente, card. Parolin: \u201cNon sono conflitti insolubili\u201d"},"content":{"rendered":"<div class=\"rwd-video\"><iframe title=\"Play 2000\" src=\"https:\/\/www.play2000.it\/play\/episode\/12165?startAt=0&amp;backToUrl=%2Fdetail%2F96%3Fepisode_id%3D12165%26season_id%3D65\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/div>\n<p style=\"text-align: center;\"><em>Il Segretario di Stato vaticano parla a Tv2000: \u201cNon dobbiamo perdere la speranza. La Giordania continui ad esercitare questo suo ruolo di pacificazione\u201d.<\/em><\/p>\n<p>\u201cLe strade ci sono, non sono conflitti insolubili\u201d. Cos\u00ec il Segretario di Stato vaticano, il card. Pietro Parolin, in un\u2019intervista del Tg2000, il telegiornale di Tv2000, a margine della Messa di inaugurazione del nuovo santuario dedicato al Battesimo di Ges\u00f9, a al-Maghtas, in Giordania in merito ai conflitti in Medio Oriente.<br \/>\n\u201cQuesti sono conflitti gravi \u2013 aggiunge il card. Parolin &#8211; che lacerano il tessuto umano e che fanno tante vittime che distruggono tante realt\u00e0, per\u00f2 le strade ci sono. Questo lo dobbiamo sempre avere presente e speriamo che la gente si metta a percorrere queste strade\u201d.<br \/>\n\u201cIn questa situazione\u201d, sottolinea il card. Parolin, \u201cnon dobbiamo perdere la speranza. D&#8217;altra parte il Papa nel denunciare indica anche delle strade. Ecco questo \u00e8 importante, che ci siano dei cammini che si dovrebbero e potrebbero percorrere\u201d. \u00c8 necessario, prosegue il segretario di Stato vaticano, \u201cla buona volont\u00e0 da parte di tutti\u201d e \u201cil Papa parla di una diplomazia del perdono, di una diplomazia della giustizia, di una diplomazia che sa farsi attenta anche alle esigenze degli altri\u201d.<br \/>\n\u201cCredo che questa celebrazione &#8211; osserva il card. Parolin &#8211; possa essere un segno di incoraggiamento. C&#8217;era il rappresentante del re e le pi\u00f9 alte autorit\u00e0 del paese. Il segnale che si \u00e8 dato \u00e8 che la Giordania deve continuare ad esercitare questo suo ruolo di pacificazione all&#8217;interno di una Regione percorsa da tante tensioni e da tanti conflitti\u201d. \u201cIl messaggio \u2013 conclude il card. Parolin ai microfoni di Tv2000 &#8211; sta proprio nella celebrazione. In tutte le parole che sono state dette, ma soprattutto nel fatto che c&#8217;\u00e8 stata tanta gente, parlavano di 6000 persone, c&#8217;era tanto entusiasmo, c&#8217;era tanta partecipazione, c&#8217;era tanta letizia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"\ufeff\ufeff\ufeff Il Segretario di Stato vaticano parla a Tv2000: \u201cNon dobbiamo perdere la speranza. La Giordania continui ad esercitare questo suo ruolo di pacificazione\u201d. \u201cLe strade ci sono, non sono conflitti insolubili\u201d. Cos\u00ec il Segretario di Stato vaticano, il card. Pietro Parolin, in un\u2019intervista del Tg2000, il telegiornale di Tv2000, a margine della Messa di [&hellip;]","protected":false},"author":22,"featured_media":224157,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,2],"tags":[],"class_list":["post-224154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-comunicati-stampa","category-comunicati"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-content\/uploads\/sites\/31\/2025\/01\/Card.-Pietro-Parolin-Tv2000-1024x576.jpg","_links":{"self":[{"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/posts\/224154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/comments?post=224154"}],"version-history":[{"count":3,"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/posts\/224154\/revisions"}],"predecessor-version":[{"id":224181,"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/posts\/224154\/revisions\/224181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/media\/224157"}],"wp:attachment":[{"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/media?parent=224154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/categories?post=224154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv2000.it\/ufficiostampa\/wp-json\/wp\/v2\/tags?post=224154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}